{"id":208,"date":"2023-01-19T20:29:14","date_gmt":"2023-01-19T19:29:14","guid":{"rendered":"http:\/\/jumi-energie.fr\/?page_id=208"},"modified":"2026-06-15T10:17:31","modified_gmt":"2026-06-15T08:17:31","slug":"pour-qui","status":"publish","type":"page","link":"https:\/\/jumi-energie.fr\/index.php\/pour-qui\/","title":{"rendered":"Pour qui?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"208\" class=\"elementor elementor-208\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4bd1439 elementor-section-full_width elementor-section-height-min-height elementor-section-content-middle elementor-section-height-default elementor-section-items-middle\" data-id=\"4bd1439\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b35f570\" data-id=\"b35f570\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-440e698 elementor-widget elementor-widget-text-editor\" data-id=\"440e698\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.1 - 17-01-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Ces pratiques douces s\u2019adaptent \u00e0 tout public : Enfants, adultes, s\u00e9niors, homme ou femme.<\/p><p>Il y a quelques pr\u00e9cautions \u00e0 prendre comme avec les personnes qui ont un pace maker, des tiges ou plaques en m\u00e9tal au niveau de la colonne vert\u00e9brale, les femmes enceintes, les \u00e9pileptiques et certaines pathologies psychiatriques.<\/p><p>Vous pouvez me consulter si vous avez une interrogation. Je vous dirais si une s\u00e9ance avec moi est possible ou pas.\u00a0<\/p><p>Tout probl\u00e8me m\u00e9dical n\u00e9cessite l\u2019avis d\u2019un professionnel de sant\u00e9. Ces m\u00e9thodes douces sont un accompagnement\u00a0 bienveillant qui ne se substitue en aucun cas au diagnostic d\u2019un m\u00e9decin ni \u00e0 un traitement m\u00e9dical. C\u2019est une d\u00e9marche personnelle pour quelqu\u2019un qui souhaite un coup de pouce suppl\u00e9mentaire \u00e0 son parcours de vie.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-27f872c\" data-id=\"27f872c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a7dd8f elementor-widget elementor-widget-image\" data-id=\"6a7dd8f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.1 - 17-01-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"612\" height=\"612\" src=\"https:\/\/jumi-energie.fr\/wp-content\/uploads\/2023\/01\/istockphoto-1177170869-612x612-3.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-427\" alt=\"\" srcset=\"https:\/\/jumi-energie.fr\/wp-content\/uploads\/2023\/01\/istockphoto-1177170869-612x612-3.jpg 612w, https:\/\/jumi-energie.fr\/wp-content\/uploads\/2023\/01\/istockphoto-1177170869-612x612-3-300x300.jpg 300w, https:\/\/jumi-energie.fr\/wp-content\/uploads\/2023\/01\/istockphoto-1177170869-612x612-3-150x150.jpg 150w, https:\/\/jumi-energie.fr\/wp-content\/uploads\/2023\/01\/istockphoto-1177170869-612x612-3-60x60.jpg 60w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-efbddb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"efbddb7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a8d0a68\" data-id=\"a8d0a68\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10fcaee elementor-widget elementor-widget-spacer\" data-id=\"10fcaee\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.10.1 - 17-01-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e2d424 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e2d424\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc82905\" data-id=\"cc82905\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-310607f elementor-widget elementor-widget-text-editor\" data-id=\"310607f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"text-decoration: underline;\">Le milieu professionnel : un monde \u00e0 part<\/span><\/p><p style=\"text-align: left;\">Particuli\u00e8rement touch\u00e9e par le bien \u00eatre dans le monde du travail,\u00a0 j\u2019ai naturellement d\u00e9di\u00e9 une partie de mon activit\u00e9 aux salari\u00e9(e)s en difficult\u00e9 dans leur milieu professionnel.<\/p><p style=\"text-align: left;\">Probl\u00e8mes relationnels, \u00e9motivit\u00e9 exacerb\u00e9e, tensions corporelles, impactent le quotidien et peuvent s\u2019inviter dans la vie priv\u00e9e. S\u2019installe alors une sensation de pesanteur physique, psychologique et \u00e9motionnelle que chacun essaie de g\u00e9rer comme il peut. C\u2019est l\u00e0 que je propose une approche douce et holistique pour comprendre et rechercher le point de d\u00e9part de chaque situation.<\/p><p style=\"text-align: left;\">Intervenante pour la semaine \u00ab\u00a0Qualit\u00e9 de Vie au Travail\u00a0\u00bb, je m\u2019adapte \u00e0 chaque salari\u00e9 et je m\u2019applique \u00e0 faire une s\u00e9ance personnalis\u00e9e dans l\u2019\u00e9coute, la bienveillance et le respect.<\/p><p style=\"text-align: left;\">Chaque entreprise peut \u00eatre impact\u00e9e et je travaille aussi en collaboration avec les \u00e9quipes dirigeantes soucieuses de leur personnel.<\/p><p style=\"text-align: left;\">Que l\u2019on soit salari\u00e9 ou dirigeant, la vision du travail peut \u00eatre diff\u00e9rente mais elle s\u2019oriente \u00a0vers un mieux-\u00eatre pour une bonne entente et une bonne synergie de groupe.<\/p><p style=\"text-align: left;\">Consultez moi pour mettre en place des s\u00e9ances \u00e9nerg\u00e9tiques b\u00e9n\u00e9fiques pour tout le monde.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9822ec2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9822ec2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0981422\" data-id=\"0981422\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8a1407 elementor-widget elementor-widget-spacer\" data-id=\"b8a1407\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ces pratiques douces s\u2019adaptent \u00e0 tout public : Enfants, adultes, s\u00e9niors, homme ou femme. Il y a quelques pr\u00e9cautions \u00e0 prendre comme avec les personnes qui ont un pace maker, &hellip; <\/p>\n","protected":false},"author":1,"featured_media":425,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-208","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/jumi-energie.fr\/index.php\/wp-json\/wp\/v2\/pages\/208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jumi-energie.fr\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jumi-energie.fr\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jumi-energie.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jumi-energie.fr\/index.php\/wp-json\/wp\/v2\/comments?post=208"}],"version-history":[{"count":65,"href":"https:\/\/jumi-energie.fr\/index.php\/wp-json\/wp\/v2\/pages\/208\/revisions"}],"predecessor-version":[{"id":1071,"href":"https:\/\/jumi-energie.fr\/index.php\/wp-json\/wp\/v2\/pages\/208\/revisions\/1071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jumi-energie.fr\/index.php\/wp-json\/wp\/v2\/media\/425"}],"wp:attachment":[{"href":"https:\/\/jumi-energie.fr\/index.php\/wp-json\/wp\/v2\/media?parent=208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}